{"id":830,"date":"2014-01-29T15:55:05","date_gmt":"2014-01-29T14:55:05","guid":{"rendered":"http:\/\/www.textile-forum-blog.org\/?p=830"},"modified":"2014-02-08T11:52:54","modified_gmt":"2014-02-08T10:52:54","slug":"a-jacquardloom-60-years-before-jacquards-invention","status":"publish","type":"post","link":"https:\/\/www.textile-forum-blog.org\/de\/2014\/01\/a-jacquardloom-60-years-before-jacquards-invention\/","title":{"rendered":"Ein \u00b4Jacquard`-Webstuhl 60 Jahren vor Jacquards \u00b4Erfindung`"},"content":{"rendered":"<p><figure id=\"attachment_836\" aria-describedby=\"caption-attachment-836\" style=\"width: 326px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.textile-forum-blog.org\/wp-content\/uploads\/2014\/01\/joseph-marie-jacquard.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-836 \" alt=\"Joseph-Marie Jacquard\" src=\"https:\/\/www.textile-forum-blog.org\/wp-content\/uploads\/2014\/01\/joseph-marie-jacquard.jpg\" width=\"326\" height=\"400\" srcset=\"https:\/\/www.textile-forum-blog.org\/wp-content\/uploads\/2014\/01\/joseph-marie-jacquard.jpg 326w, https:\/\/www.textile-forum-blog.org\/wp-content\/uploads\/2014\/01\/joseph-marie-jacquard-244x300.jpg 244w\" sizes=\"auto, (max-width: 326px) 100vw, 326px\" \/><\/a><figcaption id=\"caption-attachment-836\" class=\"wp-caption-text\">Joseph-Marie Jacquard<\/figcaption><\/figure><\/p>\n<p>Es hei\u00dft im allgemeinen: &#8220;1805 Patent on pattern weaving machine with punched cards by Joseph-Marie Charles Jacquard&#8221;.<br \/>\nEs kann sein, dass Jacquard als erster ein Patent anmelden konnte, erfunden hatte er die Technik eines vollkommen automatisierten Webstuhls mit Kartenlaufwerk nicht! Auf diese Tatsache machte uns im August ein kanadischer Leser, Herr Dr. Luc Rollland, aufmerksam, seines Zeichens Wissenschaftler und Professor am High Performance Robotics Lab\u00acoratory der Memorial University of Newfoundland in St.-John&#8217;s.<br \/>\nIm fr\u00fchen 18. Jh. besch\u00e4ftigte man sich bereits mit der Punchkar\u00actensteuerung z. B. f\u00fcr Musikauto\u00acmaten. Ein Mitarbeiter an einem der Lyoner Seidenzentren, Basile Bouchon, wendete dieses System 1725 als halbautomatische Alter\u00acnative zum Zugwebstuhl an. Sein Assistent Jean-Baptiste Falcon verbesserte diese Entwicklung bis 1728 und sp\u00e4ter (1762) nochmals zu einem vollautomatischen Webstuhl, der zu jener Zeit nur 40x verkauft wurde (http:\/\/historycomputer.com\/Dreamers\/Bouchon.html).<br \/>\nDer Erfinder Jacques Vaucanson (1707-1782), dem man 18-j\u00e4hrig bereits in Lyon ein eigenes Atelier eingerichtet hatte, besch\u00e4ftigte sich lange mit mechanischem Spielger\u00e4t, das damals in Mode war. Nach 1741 setzte man ihn auf die Entwick\u00aclung neuerer Webger\u00e4te an, weil die franz\u00f6sische Textilindustrie gegen\u00fcber England in R\u00fcckstand gekommen war. Vaucanson ver\u00acbesserte zwischen 1745 und 1750 den Webstuhl seiner Vorg\u00e4nger nochmals, sodass man seinen umfassend automatisierten Web\u00acstuhl als Weltneuheit anerkannte. Dieser Entwicklungsschritt wurde von den \u00f6rtlichen Webern aufs heftigste bek\u00e4mpft; es kam in Lyon zu Unruhen (http:\/\/historycomputer.com\/Dreamers\/Vaucanson.html).<br \/>\nErst 1805 wagte man Jacquards Patentanmeldung \u00f6ffentlich be\u00ackanntzugeben. Dass Tatsachen nicht oder nur mit langer Verz\u00f6\u00acgerung wahrgenommen werden, hat psychologische, soziale und h\u00e4ufig genug machtpolitische Gr\u00fcnde.<\/p>","protected":false},"excerpt":{"rendered":"<p>Es hei\u00dft im allgemeinen: &#8220;1805 Patent on pattern weaving machine with punched cards by Joseph-Marie Charles Jacquard&#8221;. Es kann sein, dass Jacquard als erster ein Patent anmelden konnte, erfunden hatte&#8230;<\/p>\n","protected":false},"author":1,"featured_media":835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notes"],"_links":{"self":[{"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/posts\/830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/comments?post=830"}],"version-history":[{"count":0,"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/posts\/830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/media\/835"}],"wp:attachment":[{"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/media?parent=830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/categories?post=830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.textile-forum-blog.org\/de\/wp-json\/wp\/v2\/tags?post=830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}